{"id":11063,"date":"2022-01-10T20:43:27","date_gmt":"2022-01-10T20:43:27","guid":{"rendered":"https:\/\/oliveolives.com\/?post_type=product&#038;p=11063"},"modified":"2026-05-13T01:54:52","modified_gmt":"2026-05-13T01:54:52","slug":"whole-green-olives-campo-real-style","status":"publish","type":"product","link":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/","title":{"rendered":"Whole Green Olives &#8216;Campo Real&#8217; Style"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":11236,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[106,35,29],"product_tag":[],"class_list":{"0":"post-11063","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-oliveolives","7":"product_cat-olives","8":"product_cat-pantry","10":"first","11":"instock","12":"purchasable","13":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Whole Green Olives &#039;Campo Real&#039; Style<\/title>\n<meta name=\"description\" content=\"Whole Green Olives &#039;Campo Real&#039; Style Olive &amp; Olives\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Whole Green Olives &#039;Campo Real&#039; Style\" \/>\n<meta property=\"og:description\" content=\"Whole Green Olives &#039;Campo Real&#039; Style Olive &amp; Olives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/\" \/>\n<meta property=\"og:site_name\" content=\"Olive &amp; Olives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/olive.olives\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:54:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.oliveolives.com\/wp-content\/uploads\/2022\/01\/boutique-campo2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"550\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/\",\"url\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/\",\"name\":\"Whole Green Olives 'Campo Real' Style\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.oliveolives.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/boutique-campo2.jpg\",\"datePublished\":\"2022-01-10T20:43:27+00:00\",\"dateModified\":\"2026-05-13T01:54:52+00:00\",\"description\":\"Whole Green Olives 'Campo Real' Style Olive &amp; Olives\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.oliveolives.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/boutique-campo2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.oliveolives.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/boutique-campo2.jpg\",\"width\":550,\"height\":625},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/produit\\\/whole-green-olives-campo-real-style\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.oliveolives.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.oliveolives.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Whole Green Olives &lsquo;Campo Real&rsquo; Style\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.oliveolives.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.oliveolives.com\\\/fr\\\/\",\"name\":\"Olive &amp; Olives\",\"description\":\"Les sp\u00e9cialistes des huiles d\u2019olive extra vierges de qualit\u00e9\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.oliveolives.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whole Green Olives 'Campo Real' Style","description":"Whole Green Olives 'Campo Real' Style Olive &amp; Olives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/","og_locale":"en_US","og_type":"article","og_title":"Whole Green Olives 'Campo Real' Style","og_description":"Whole Green Olives 'Campo Real' Style Olive &amp; Olives","og_url":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/","og_site_name":"Olive &amp; Olives","article_publisher":"https:\/\/www.facebook.com\/olive.olives\/","article_modified_time":"2026-05-13T01:54:52+00:00","og_image":[{"width":550,"height":625,"url":"https:\/\/www.oliveolives.com\/wp-content\/uploads\/2022\/01\/boutique-campo2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/","url":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/","name":"Whole Green Olives 'Campo Real' Style","isPartOf":{"@id":"https:\/\/www.oliveolives.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/#primaryimage"},"image":{"@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/#primaryimage"},"thumbnailUrl":"https:\/\/www.oliveolives.com\/wp-content\/uploads\/2022\/01\/boutique-campo2.jpg","datePublished":"2022-01-10T20:43:27+00:00","dateModified":"2026-05-13T01:54:52+00:00","description":"Whole Green Olives 'Campo Real' Style Olive &amp; Olives","breadcrumb":{"@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/#primaryimage","url":"https:\/\/www.oliveolives.com\/wp-content\/uploads\/2022\/01\/boutique-campo2.jpg","contentUrl":"https:\/\/www.oliveolives.com\/wp-content\/uploads\/2022\/01\/boutique-campo2.jpg","width":550,"height":625},{"@type":"BreadcrumbList","@id":"https:\/\/www.oliveolives.com\/en\/produit\/whole-green-olives-campo-real-style\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.oliveolives.com\/en\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.oliveolives.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Whole Green Olives &lsquo;Campo Real&rsquo; Style"}]},{"@type":"WebSite","@id":"https:\/\/www.oliveolives.com\/fr\/#website","url":"https:\/\/www.oliveolives.com\/fr\/","name":"Olive &amp; Olives","description":"Les sp\u00e9cialistes des huiles d\u2019olive extra vierges de qualit\u00e9","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oliveolives.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/product\/11063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/comments?post=11063"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/media\/11236"}],"wp:attachment":[{"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/media?parent=11063"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/product_brand?post=11063"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/product_cat?post=11063"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.oliveolives.com\/en\/wp-json\/wp\/v2\/product_tag?post=11063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}